{"id":5911,"date":"2021-10-11T08:13:20","date_gmt":"2021-10-11T06:13:20","guid":{"rendered":"https:\/\/www.borgione.it\/blog\/?p=5911"},"modified":"2022-12-19T16:49:52","modified_gmt":"2022-12-19T15:49:52","slug":"pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment","status":"publish","type":"post","link":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/","title":{"rendered":"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d"},"content":{"rendered":"<p>La peculiarit\u00e0 che accomuna i vari terapisti dell\u2019et\u00e0 evolutiva \u00e8 quella di doversi rapportare con un essere in continua evoluzione e in stretta relazione con la famiglia: ovvero il bambino.<\/p>\n<p>Questi due elementi determinano infatti una netta differenza rispetto al lavoro con gli adulti e condizionano necessariamente il tipo di approccio da utilizzare (vd. Tabella di approfondimento).<\/p>\n<p>Infatti, nonostante possano essere molteplici le motivazioni che porteranno una famiglia a rivolgersi ad un Terapista dell\u2019area pediatrica in ambito Ri-abilitativo, quello che di certo accumuner\u00e0 in maniera trasversale i vari operatori, e che condizioner\u00e0 il risultato del trattamento stesso, sar\u00e0 il tipo di relazione terapeutica instaurata, tanto con il paziente (quindi il bambino) che con la sua famiglia.<\/p>\n<p>I genitori sono infatti \u201ci massimi esperti dei propri figli\u201d e devono essere necessariamente coinvolti nella cura, nelle decisioni mediche e nelle attivit\u00e0 assistenziali.<\/p>\n<p>Ecco che entriamo nel merito del cos\u00ec detto <strong><em>\u201cFamily-Centered Care\u201d (FCC<\/em>)<\/strong> o \u201c<strong><em>Approccio Centrato sulla Famiglia\u201d (ACF).<\/em><\/strong><\/p>\n<p>Un approccio, nato negli anni \u201880 nelle terapie intensive neonatali Statunitensi, basato su attitudini professionali, modi di fare e di essere, cos\u00ec come modalit\u00e0 operative ed organizzative, che <em>\u201criconosce e valorizza la famiglia come maggior esperta del bambino, come intermediaria tra bambino e mondo esterno e come elemento principale di influenza sullo sviluppo stesso\u201d.<\/em><\/p>\n<p>Grazie a questo tipo di approccio, supportato dagli studi sul bonding e sull\u2019importanza del contatto fisico ed emotivo tra genitore e bambino, \u00e8 stata messa in evidenza l\u2019importanza e la necessit\u00e0 di spostarci da un modello centrato esclusivamente sul bambino, in cui il principale agente di cambiamento veniva considerato il <strong>terapista<\/strong>, ad un modello in cui viene al contrario sostenuto e riconosciuto il ruolo fondamentale della <strong>famiglia<\/strong>, come \u201cfonte principale di stabilit\u00e0 e supporto\u201d nella vita del bambino stesso. (Tabella di approfondimento n. 2)<\/p>\n<p>Oltre a questo l\u2019ACF \u00a0ha permesso di diffondere un\u2019ottica pi\u00f9 positiva, centrata sulle competenze e le capacit\u00e0 del bambino piuttosto che sulle sue problematiche, creando un sistema basato sulla collaborazione, la condivisione e il sostegno reciproco tra terapista e famiglia, una partnership in continua evoluzione e cambiamento, adattabile e flessibile in base ai nuovi obiettivi e alle nuove conquiste, in cui i genitori possano sentirsi protagonisti assieme al figlio e in grado di operare, anche in autonomia (Tabella di approfondimento n.3).<\/p>\n<p>Un concetto base del FCC \u00e8 infatti quello dell\u2019\u201cempowerment\u201d, ovvero dell\u2019importanza di riconoscere, enfatizzare e rinforzare il ruolo genitoriale, di valorizzare, sostenere e migliorare le abilit\u00e0 della famiglia stessa affinch\u00e9 non si crei n\u00e9 una dipendenza n\u00e9 una competizione con il terapista e la famiglia possa diventare parte attiva nel processo di cura e ri-abilitazione.<\/p>\n<p>Gli operatori assumono quindi un ruolo di \u201cfacilitatori\u201d, per accompagnare i genitori alla scoperta e allo sviluppo delle loro abilit\u00e0, con la consapevolezza di fondo che il successo del trattamento dipender\u00e0 proprio dalla condivisione, comprensione e accettazione da parte della famiglia degli obiettivi prefissati e individuati durante il percorso e che il tutto partir\u00e0 proprio dalla prima accoglienza e valutazione.(Tabella di approfondimento n. 4)<\/p>\n<p><img decoding=\"async\" class=\"wp-image-5915 aligncenter\" src=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/tabella1.png\" alt=\"\" width=\"927\" height=\"571\" srcset=\"https:\/\/www.borgione.it\/blog\/wp-content\/uploads\/2021\/10\/tabella1.png%20993w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella1-300x185.png%20300w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella1-768x473.png%20768w\" sizes=\"(max-width: 927px) 100vw, 927px\" \/><\/p>\n<p><img decoding=\"async\" class=\"wp-image-5916 aligncenter\" src=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/tabella2.png\" alt=\"\" width=\"941\" height=\"344\" srcset=\"https:\/\/www.borgione.it\/blog\/wp-content\/uploads\/2021\/10\/tabella2.png%20989w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella2-300x110.png%20300w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella2-768x281.png%20768w\" sizes=\"(max-width: 941px) 100vw, 941px\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-5917 aligncenter\" src=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/tabella3.png\" alt=\"\" width=\"1078\" height=\"375\" srcset=\"https:\/\/www.borgione.it\/blog\/wp-content\/uploads\/2021\/10\/tabella3.png%201078w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella3-300x104.png%20300w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella3-1024x356.png%201024w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella3-768x267.png%20768w\" sizes=\"(max-width: 1078px) 100vw, 1078px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignleft size-full wp-image-5918\" src=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/tabella4.png\" alt=\"\" width=\"1080\" height=\"691\" srcset=\"https:\/\/www.borgione.it\/blog\/wp-content\/uploads\/2021\/10\/tabella4.png%201080w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella4-300x192.png%20300w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella4-1024x655.png%201024w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2021\/10\/tabella4-768x491.png%20768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>BIBLIOGRAFIA E SITOGRAFIA:<\/p>\n<p>Dispense Master in Fisioterapia Pediatrica \u2013 Corso \u201cCore Competence\u201d \u2013 Dott. Ft adrienne Davidson<\/p>\n<p>www.canchild.ca<\/p>\n<p>www.infermiereonline.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La peculiarit\u00e0 che accomuna i vari terapisti dell\u2019et\u00e0 evolutiva \u00e8 quella di doversi rapportare con un essere in continua evoluzione e in stretta relazione con la famiglia: ovvero il bambino. Questi due elementi determinano infatti una netta differenza rispetto al lavoro con gli adulti e condizionano necessariamente il tipo di approccio da utilizzare (vd. Tabella [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":5913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[7,1],"tags":[],"class_list":{"0":"post-5911","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-pedagogia","8":"category-notizie","9":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d - Blog - Borgione Centro Didattico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d - Blog - Borgione Centro Didattico\" \/>\n<meta property=\"og:description\" content=\"La peculiarit\u00e0 che accomuna i vari terapisti dell\u2019et\u00e0 evolutiva \u00e8 quella di doversi rapportare con un essere in continua evoluzione e in stretta relazione con la famiglia: ovvero il bambino. Questi due elementi determinano infatti una netta differenza rispetto al lavoro con gli adulti e condizionano necessariamente il tipo di approccio da utilizzare (vd. Tabella [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Borgione Centro Didattico\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-11T06:13:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-19T15:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dott.ssa Valentina Torelli- Fisioterapista\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dott.ssa Valentina Torelli- Fisioterapista\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\\\/\"},\"author\":{\"name\":\"Dott.ssa Valentina Torelli- Fisioterapista\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/2022733dbc9f003e6a79907800f92b71\"},\"headline\":\"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d\",\"datePublished\":\"2021-10-11T06:13:20+00:00\",\"dateModified\":\"2022-12-19T15:49:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\\\/\"},\"wordCount\":533,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png\",\"articleSection\":[\"Angolo del Terapista\",\"Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\\\/\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\\\/\",\"name\":\"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d - Blog - Borgione Centro Didattico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png\",\"datePublished\":\"2021-10-11T06:13:20+00:00\",\"dateModified\":\"2022-12-19T15:49:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/2022733dbc9f003e6a79907800f92b71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage\",\"url\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png\",\"contentUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png\",\"width\":1600,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/\",\"name\":\"Blog - Borgione Centro Didattico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/?s=%7Bsearch_term_string%7D\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/2022733dbc9f003e6a79907800f92b71\",\"name\":\"Dott.ssa Valentina Torelli- Fisioterapista\",\"sameAs\":[\"@lafisioterapistadellemamme\"],\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/author\\\/dott-ssa-valentina-torelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d - Blog - Borgione Centro Didattico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/","og_locale":"it_IT","og_type":"article","og_title":"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d - Blog - Borgione Centro Didattico","og_description":"La peculiarit\u00e0 che accomuna i vari terapisti dell\u2019et\u00e0 evolutiva \u00e8 quella di doversi rapportare con un essere in continua evoluzione e in stretta relazione con la famiglia: ovvero il bambino. Questi due elementi determinano infatti una netta differenza rispetto al lavoro con gli adulti e condizionano necessariamente il tipo di approccio da utilizzare (vd. Tabella [&hellip;]","og_url":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/","og_site_name":"Blog - Borgione Centro Didattico","article_published_time":"2021-10-11T06:13:20+00:00","article_modified_time":"2022-12-19T15:49:52+00:00","og_image":[{"width":1600,"height":1080,"url":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png","type":"image\/png"}],"author":"Dott.ssa Valentina Torelli- Fisioterapista","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dott.ssa Valentina Torelli- Fisioterapista","Est. reading time":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#article","isPartOf":{"@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/"},"author":{"name":"Dott.ssa Valentina Torelli- Fisioterapista","@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/2022733dbc9f003e6a79907800f92b71"},"headline":"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d","datePublished":"2021-10-11T06:13:20+00:00","dateModified":"2022-12-19T15:49:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/"},"wordCount":533,"commentCount":0,"image":{"@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage"},"thumbnailUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png","articleSection":["Angolo del Terapista","Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/","url":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/","name":"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d - Blog - Borgione Centro Didattico","isPartOf":{"@id":"https:\/\/www.borgione.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage"},"image":{"@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage"},"thumbnailUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png","datePublished":"2021-10-11T06:13:20+00:00","dateModified":"2022-12-19T15:49:52+00:00","author":{"@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/2022733dbc9f003e6a79907800f92b71"},"breadcrumb":{"@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#primaryimage","url":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png","contentUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2021\/10\/le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment-1.png","width":1600,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.borgione.it\/blog\/pedagogia-le-basi-di-una-relazione-terapeutica-efficace-i-concetti-di-acf-e-empowerment#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.borgione.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Le basi di una relazione terapeutica efficace: i concetti di \u201cacf\u201d e \u201cempowerment\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.borgione.it\/blog\/#website","url":"https:\/\/www.borgione.it\/blog\/","name":"Blog - Borgione Centro Didattico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.borgione.it\/blog\/?s=%7Bsearch_term_string%7D"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/2022733dbc9f003e6a79907800f92b71","name":"Dott.ssa Valentina Torelli- Fisioterapista","sameAs":["@lafisioterapistadellemamme"],"url":"https:\/\/www.borgione.it\/blog\/author\/dott-ssa-valentina-torelli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/5911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/comments?post=5911"}],"version-history":[{"count":3,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/5911\/revisions"}],"predecessor-version":[{"id":5914,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/5911\/revisions\/5914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/media\/5913"}],"wp:attachment":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/media?parent=5911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/categories?post=5911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/tags?post=5911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}