{"id":5007,"date":"2020-09-02T15:46:03","date_gmt":"2020-09-02T13:46:03","guid":{"rendered":"https:\/\/www.borgione.it\/blog\/?p=5007"},"modified":"2022-06-29T10:21:51","modified_gmt":"2022-06-29T08:21:51","slug":"5007-2","status":"publish","type":"post","link":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/","title":{"rendered":"Nuovo catalogo nido-infanzia Borgione 2020\/2021"},"content":{"rendered":"<p>E\u2019 arrivato il nuovo catalogo Borgione nido\/infanzia 2020-2021!<\/p>\n<p>Da oggi potrete sfogliare e scoprire <strong>centinaia di novit\u00e0 tra <a href=\"https:\/\/www.borgione.it\/cancelleria\">cancelleria<\/a>, <a href=\"https:\/\/www.borgione.it\/creativita_2\">creativit\u00e0<\/a>, <a href=\"https:\/\/www.borgione.it\/giochi-educativi-per-bambini\">giochi<\/a> e <a href=\"https:\/\/www.borgione.it\/arredi\">arredi<\/a><\/strong>&#8230;<br \/>\ntra cui tantissimi prodotti <em>Ecofriendly<\/em>, realizzati con materiali riciclati e riciclabili!<\/p>\n<p>Inoltre, per dare un ulteriore contributo alla tutela dell&#8217;ambiente, il catalogo \u00e8 stato stampato su carta PEFC con energia 100% green!<\/p>\n<p>Al suo interno troverete tutto il necessario per:<\/p>\n<p>&#8211; organizzare attivit\u00e0 espressive e artistiche<\/p>\n<p>&#8211; proporre attivit\u00e0 sensoriali per lo sviluppo del bambino<\/p>\n<p>&#8211; stimolare il linguaggio<\/p>\n<p>&#8211; organizzare attivit\u00e0 psicomotorie<\/p>\n<p>&#8211; <a href=\"https:\/\/www.borgione.it\/arredi\/arredo-ufficio\">arredare spazi della scuola, uffici, segreterie e studi professionali<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/www.borgione.it\/cataloghi\/cataloghi\/nidi\">Sfoglia il catalogo Borgione 2020\/2021<\/a><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>Alcune delle novit\u00e0 selezionate per voi<\/strong><\/h2>\n<p>Tra le novit\u00e0 abbiamo riservato uno spazio a tutti gli <a href=\"https:\/\/www.borgione.it\/igiene-e-sicurezza_1\">articoli necessari per rispettare le nuove norme igienico-sanitarie<\/a>: detergenti per gli ambienti, gel igienizzanti, disinfettanti, mascherine lavabili, visiere e tanto altro ancora, per concedervi un rientro a scuola in piena sicurezza!<\/p>\n<p>Per il \u201c<a href=\"https:\/\/www.borgione.it\/cancelleria\/back-to-school_3\">back to school<\/a>\u201d troverete tutto l\u2019occorrente come quaderni, raccoglitori, penne, matite e molto altro per riempire gli zaini dei vostri bambini. L\u2019attesa per il rientro a scuola, quest\u2019anno, si fa sentire ancora di pi\u00f9, perci\u00f2 non fatevi cogliere impreparati!<\/p>\n<p><strong>Infine, scopri i nuovi prodotti di Toys for Life!<\/strong><\/p>\n<p>Una nuova filosofia, quella dell\u2019<em>homeschooling<\/em>, accompagna i prodotti di <a href=\"https:\/\/www.borgione.it\/toys-for-life\">Toys for Life<\/a>, adatti per bambini con un\u2019et\u00e0 compresa tra i 3 e 7 anni.<\/p>\n<p>Qualit\u00e0, sicurezza e durata nel tempo sono i valori principali che caratterizzano la produzione di questi articoli, studiati per imparare le prime nozioni della matematica, per sviluppare il linguaggio e per affinare la motricit\u00e0 fine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 arrivato il nuovo catalogo Borgione nido\/infanzia 2020-2021! Da oggi potrete sfogliare e scoprire centinaia di novit\u00e0 tra cancelleria, creativit\u00e0, giochi e arredi&#8230; tra cui tantissimi prodotti Ecofriendly, realizzati con materiali riciclati e riciclabili! Inoltre, per dare un ulteriore contributo alla tutela dell&#8217;ambiente, il catalogo \u00e8 stato stampato su carta PEFC con energia 100% green! [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-5007","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-notizie","8":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuovo catalogo nido-infanzia Borgione 2020\/2021 - Blog - Borgione Centro Didattico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo catalogo nido-infanzia Borgione 2020\/2021 - Blog - Borgione Centro Didattico\" \/>\n<meta property=\"og:description\" content=\"E\u2019 arrivato il nuovo catalogo Borgione nido\/infanzia 2020-2021! Da oggi potrete sfogliare e scoprire centinaia di novit\u00e0 tra cancelleria, creativit\u00e0, giochi e arredi&#8230; tra cui tantissimi prodotti Ecofriendly, realizzati con materiali riciclati e riciclabili! Inoltre, per dare un ulteriore contributo alla tutela dell&#8217;ambiente, il catalogo \u00e8 stato stampato su carta PEFC con energia 100% green! [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Borgione Centro Didattico\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T13:46:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-29T08:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2020\/09\/catalogo_1-1024x759.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"759\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Michela Calculli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michela Calculli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\\\/\"},\"author\":{\"name\":\"Michela Calculli\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/9aeaed96076b386bcc2570e0d0b7dc7c\"},\"headline\":\"Nuovo catalogo nido-infanzia Borgione 2020\\\/2021\",\"datePublished\":\"2020-09-02T13:46:03+00:00\",\"dateModified\":\"2022-06-29T08:21:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\\\/\"},\"wordCount\":263,\"commentCount\":29,\"image\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/catalogo_1.png\",\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\\\/\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\\\/\",\"name\":\"Nuovo catalogo nido-infanzia Borgione 2020\\\/2021 - Blog - Borgione Centro Didattico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/catalogo_1.png\",\"datePublished\":\"2020-09-02T13:46:03+00:00\",\"dateModified\":\"2022-06-29T08:21:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/9aeaed96076b386bcc2570e0d0b7dc7c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage\",\"url\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/catalogo_1.png\",\"contentUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/catalogo_1.png\",\"width\":4032,\"height\":2987},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo catalogo nido-infanzia Borgione 2020\\\/2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/\",\"name\":\"Blog - Borgione Centro Didattico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/?s=%7Bsearch_term_string%7D\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/9aeaed96076b386bcc2570e0d0b7dc7c\",\"name\":\"Michela Calculli\",\"description\":\"Una laurea in Economia, tante esperienze di lavoro tra ICT, Fisco e Comunicazione. Da oltre 10 anni si occupa di creazione e pianificazione di contenuti professionali scritti per il web.\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/author\\\/michela-calculli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo catalogo nido-infanzia Borgione 2020\/2021 - Blog - Borgione Centro Didattico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo catalogo nido-infanzia Borgione 2020\/2021 - Blog - Borgione Centro Didattico","og_description":"E\u2019 arrivato il nuovo catalogo Borgione nido\/infanzia 2020-2021! Da oggi potrete sfogliare e scoprire centinaia di novit\u00e0 tra cancelleria, creativit\u00e0, giochi e arredi&#8230; tra cui tantissimi prodotti Ecofriendly, realizzati con materiali riciclati e riciclabili! Inoltre, per dare un ulteriore contributo alla tutela dell&#8217;ambiente, il catalogo \u00e8 stato stampato su carta PEFC con energia 100% green! [&hellip;]","og_url":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/","og_site_name":"Blog - Borgione Centro Didattico","article_published_time":"2020-09-02T13:46:03+00:00","article_modified_time":"2022-06-29T08:21:51+00:00","og_image":[{"width":1024,"height":759,"url":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2020\/09\/catalogo_1-1024x759.png","type":"image\/png"}],"author":"Michela Calculli","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michela Calculli","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#article","isPartOf":{"@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/"},"author":{"name":"Michela Calculli","@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/9aeaed96076b386bcc2570e0d0b7dc7c"},"headline":"Nuovo catalogo nido-infanzia Borgione 2020\/2021","datePublished":"2020-09-02T13:46:03+00:00","dateModified":"2022-06-29T08:21:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/"},"wordCount":263,"commentCount":29,"image":{"@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage"},"thumbnailUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2020\/09\/catalogo_1.png","articleSection":["Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/","url":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/","name":"Nuovo catalogo nido-infanzia Borgione 2020\/2021 - Blog - Borgione Centro Didattico","isPartOf":{"@id":"https:\/\/www.borgione.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage"},"image":{"@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage"},"thumbnailUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2020\/09\/catalogo_1.png","datePublished":"2020-09-02T13:46:03+00:00","dateModified":"2022-06-29T08:21:51+00:00","author":{"@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/9aeaed96076b386bcc2570e0d0b7dc7c"},"breadcrumb":{"@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#primaryimage","url":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2020\/09\/catalogo_1.png","contentUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2020\/09\/catalogo_1.png","width":4032,"height":2987},{"@type":"BreadcrumbList","@id":"https:\/\/www.borgione.it\/blog\/nuovo-catalogo-nido-infanzia-borgione-2020-2021#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.borgione.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuovo catalogo nido-infanzia Borgione 2020\/2021"}]},{"@type":"WebSite","@id":"https:\/\/www.borgione.it\/blog\/#website","url":"https:\/\/www.borgione.it\/blog\/","name":"Blog - Borgione Centro Didattico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.borgione.it\/blog\/?s=%7Bsearch_term_string%7D"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/9aeaed96076b386bcc2570e0d0b7dc7c","name":"Michela Calculli","description":"Una laurea in Economia, tante esperienze di lavoro tra ICT, Fisco e Comunicazione. Da oltre 10 anni si occupa di creazione e pianificazione di contenuti professionali scritti per il web.","url":"https:\/\/www.borgione.it\/blog\/author\/michela-calculli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/5007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/comments?post=5007"}],"version-history":[{"count":5,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/5007\/revisions"}],"predecessor-version":[{"id":6658,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/5007\/revisions\/6658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/media\/5009"}],"wp:attachment":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/media?parent=5007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/categories?post=5007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/tags?post=5007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}