{"id":2536,"date":"2018-06-06T09:32:49","date_gmt":"2018-06-06T07:32:49","guid":{"rendered":"https:\/\/www.borgione.it\/blog?p=2536"},"modified":"2020-07-28T14:45:40","modified_gmt":"2020-07-28T12:45:40","slug":"tempere-sensoriali-cosa-sono-e-come-utilizzarle","status":"publish","type":"post","link":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/","title":{"rendered":"Colori a tempera sensoriali: cosa sono e come utilizzarli!"},"content":{"rendered":"<p>La fantasia \u00e8 come la marmellata, bisogna che sia spalmata su una solida fetta di pane.<\/p>\n<p><em>Italo Calvino<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>E i bambini sono golosi di marmellata! Sono pieni di fantasia e, s\u00ec, fanno un sacco di briciole!<\/p>\n<p>Ma questi 2 elementi, immaginazione e briciole, possono dare il via a grandi opere d&#8217;arte.<\/p>\n<p>Il kit \u201c<strong><a href=\"https:\/\/www.borgione.it\/creativita\/colori-per-dipingere\/tempere-speciali\/crea-tempera-sensoriale-gr-870\">Crea tempera sensoriale<\/a><\/strong>\u201d \u00e8 infatti una collezione di materiali <em>sbriciolati<\/em> da aggiungere alla tempera a dita per renderla &#8220;sensoriale&#8221;, ottenendo fino a 10 diverse texture. Si avr\u00e0 cos\u00ec un colore a dita per bambini sicuro, divertente e innovativo! <strong>E i bimbi saranno incoraggiati a sprigionare la loro creativit\u00e0, mentre eserciteranno la motricit\u00e0 fine e affineranno le loro abilit\u00e0 propriocettive e sensoriali.<\/strong><\/p>\n<p class=\"alignnone\"><a href=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/75415-fingerpaint-sensations_image-sample1-e1527233796175.jpg\"><img decoding=\"async\" class=\"size-full wp-image-2538 alignleft\" src=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/75415-fingerpaint-sensations_image-sample1-e1527233796175.jpg\" alt=\"75415-fingerpaint-sensations_image-sample1\" width=\"256\" height=\"339\" srcset=\"https:\/\/www.borgione.it\/blog\/wp-content\/uploads\/2018\/05\/75415-fingerpaint-sensations_image-sample1-e1527233796175.jpg%20256w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2018\/05\/75415-fingerpaint-sensations_image-sample1-e1527233796175-227x300.jpg%20227w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/a>Ogni materiale di questo kit \u00e8 in un sacchetto a s\u00e9: il bimbo pu\u00f2 prima iniziare a familiarizzare con le diverse grane e texture, magari a occhi chiusi, solo infilando la mano nel sacchetto. Gli si pu\u00f2 chiedere di provare a descrivere le sensazioni, sollecitandolo a migliorare il suo vocabolario: sentir\u00e0 infatti qualcosa di granuloso, di ruvido, a pallini, a filetti, liscio&#8230;<\/p>\n<p>In seguito, il bambino unisce un materiale ai colori a tempera a dita, mescolandoli in una ciotolina e decidendo in quale proporzione farlo, per ottenere un colore pi\u00f9 o meno denso; cos\u00ec per tutti i diversi materiali.<\/p>\n<p>A questo punto la fantasia solleticata dai colori si unisce alla suggestione delle sensazioni tattili e visive: il bambino inizia a disegnare, associando ai soggetti rappresentati non solo una tinta ma anche una \u201cconsistenza\u201d. Pu\u00f2 realizzare un deserto giallo&#8230;e sabbioso! Un prato verde, pieno di fili&#8230;ed ecco l&#8217;erba! Un mare blu e azzurro pieno di pallini, perch\u00e9 tuffandosi si creano mille bolle!<\/p>\n<p><strong>Ma questi sono solo alcuni suggerimenti: i bambini ci superano in immaginazione e potranno persino creare animali fantastici, con penne morbide e ispidi musetti!<\/strong><\/p>\n<p>Per focalizzare l&#8217;attenzione sull&#8217;esperienza tattile, si potrebbero bendare i bambini: loro si faranno grasse risate a dipingere a occhi chiusi e i risultati saranno sorprendenti! L&#8217;idea del soggetto da rappresentare questa volta parte infatti dalla percezione tattile: non decido di disegnare un piatto di pasta, ma sento un materiale morbido, filamentoso, dalla sezione rotonda&#8230;e penso agli spaghetti!<\/p>\n<p>Inoltre, pur non vedendo i segni tracciati, i bambini sono incredibilmente consci di cosa e come stanno dipingendo: lo sentono con le dita!!! E saranno quindi molto gratificati nel constatare lo splendido risultato.<\/p>\n<p>Vuoi vedere? Guarda il video qui sotto!<\/p>\n<p><iframe title=\"Crea tempera sensoriale\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/pHppeCC6cUg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_781\" style=\"width: 190px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2015\/11\/danae.png\"><img decoding=\"async\" aria-describedby=\"caption-attachment-781\" class=\"size-full wp-image-781\" src=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2015\/11\/danae.png\" alt=\"Danae\" width=\"180\" height=\"180\" srcset=\"https:\/\/www.borgione.it\/blog\/wp-content\/uploads\/2015\/11\/danae.png%20180w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2015\/11\/danae-150x150.png%20150w,%20https:\/blog.borgione.it\/wp-content\/uploads\/2015\/11\/danae-60x60.png%2060w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a><p id=\"caption-attachment-781\" class=\"wp-caption-text\">Danae<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La fantasia \u00e8 come la marmellata, bisogna che sia spalmata su una solida fetta di pane. Italo Calvino &nbsp; E i bambini sono golosi di marmellata! Sono pieni di fantasia e, s\u00ec, fanno un sacco di briciole! Ma questi 2 elementi, immaginazione e briciole, possono dare il via a grandi opere d&#8217;arte. Il kit \u201cCrea [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[8,1],"tags":[143,246,403,402],"class_list":{"0":"post-2536","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-creativita","8":"category-notizie","9":"tag-colori","10":"tag-colori-a-dita","11":"tag-colori-a-tempera","12":"tag-tempere-sensoriali","13":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colori a tempera sensoriali: cosa sono e come utilizzarli! - Blog - Borgione Centro Didattico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colori a tempera sensoriali: cosa sono e come utilizzarli! - Blog - Borgione Centro Didattico\" \/>\n<meta property=\"og:description\" content=\"La fantasia \u00e8 come la marmellata, bisogna che sia spalmata su una solida fetta di pane. Italo Calvino &nbsp; E i bambini sono golosi di marmellata! Sono pieni di fantasia e, s\u00ec, fanno un sacco di briciole! Ma questi 2 elementi, immaginazione e briciole, possono dare il via a grandi opere d&#8217;arte. Il kit \u201cCrea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Borgione Centro Didattico\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-06T07:32:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-28T12:45:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/feature-image-fingerpaintsense.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/035ab9f79e06957439022325c63541eb\"},\"headline\":\"Colori a tempera sensoriali: cosa sono e come utilizzarli!\",\"datePublished\":\"2018-06-06T07:32:49+00:00\",\"dateModified\":\"2020-07-28T12:45:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\\\/\"},\"wordCount\":418,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/feature-image-fingerpaintsense.jpg\",\"keywords\":[\"colori\",\"colori a dita\",\"colori a tempera\",\"tempere sensoriali\"],\"articleSection\":[\"Creativit\u00e0\",\"Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\\\/\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\\\/\",\"name\":\"Colori a tempera sensoriali: cosa sono e come utilizzarli! - Blog - Borgione Centro Didattico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/feature-image-fingerpaintsense.jpg\",\"datePublished\":\"2018-06-06T07:32:49+00:00\",\"dateModified\":\"2020-07-28T12:45:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/035ab9f79e06957439022325c63541eb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage\",\"url\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/feature-image-fingerpaintsense.jpg\",\"contentUrl\":\"https:\\\/\\\/borgione.kleecks-cdn.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/feature-image-fingerpaintsense.jpg\",\"width\":620,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colori a tempera sensoriali: cosa sono e come utilizzarli!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/\",\"name\":\"Blog - Borgione Centro Didattico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/?s=%7Bsearch_term_string%7D\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/#\\\/schema\\\/person\\\/035ab9f79e06957439022325c63541eb\",\"name\":\"Redazione\",\"url\":\"https:\\\/\\\/www.borgione.it\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colori a tempera sensoriali: cosa sono e come utilizzarli! - Blog - Borgione Centro Didattico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/","og_locale":"it_IT","og_type":"article","og_title":"Colori a tempera sensoriali: cosa sono e come utilizzarli! - Blog - Borgione Centro Didattico","og_description":"La fantasia \u00e8 come la marmellata, bisogna che sia spalmata su una solida fetta di pane. Italo Calvino &nbsp; E i bambini sono golosi di marmellata! Sono pieni di fantasia e, s\u00ec, fanno un sacco di briciole! Ma questi 2 elementi, immaginazione e briciole, possono dare il via a grandi opere d&#8217;arte. Il kit \u201cCrea [&hellip;]","og_url":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/","og_site_name":"Blog - Borgione Centro Didattico","article_published_time":"2018-06-06T07:32:49+00:00","article_modified_time":"2020-07-28T12:45:40+00:00","og_image":[{"width":620,"height":380,"url":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/feature-image-fingerpaintsense.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#article","isPartOf":{"@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/"},"author":{"name":"Redazione","@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/035ab9f79e06957439022325c63541eb"},"headline":"Colori a tempera sensoriali: cosa sono e come utilizzarli!","datePublished":"2018-06-06T07:32:49+00:00","dateModified":"2020-07-28T12:45:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/"},"wordCount":418,"commentCount":0,"image":{"@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage"},"thumbnailUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/feature-image-fingerpaintsense.jpg","keywords":["colori","colori a dita","colori a tempera","tempere sensoriali"],"articleSection":["Creativit\u00e0","Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/","url":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/","name":"Colori a tempera sensoriali: cosa sono e come utilizzarli! - Blog - Borgione Centro Didattico","isPartOf":{"@id":"https:\/\/www.borgione.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage"},"image":{"@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage"},"thumbnailUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/feature-image-fingerpaintsense.jpg","datePublished":"2018-06-06T07:32:49+00:00","dateModified":"2020-07-28T12:45:40+00:00","author":{"@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/035ab9f79e06957439022325c63541eb"},"breadcrumb":{"@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#primaryimage","url":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/feature-image-fingerpaintsense.jpg","contentUrl":"https:\/\/borgione.kleecks-cdn.com\/blog\/wp-content\/uploads\/2018\/05\/feature-image-fingerpaintsense.jpg","width":620,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/www.borgione.it\/blog\/tempere-sensoriali-cosa-sono-e-come-utilizzarle#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.borgione.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Colori a tempera sensoriali: cosa sono e come utilizzarli!"}]},{"@type":"WebSite","@id":"https:\/\/www.borgione.it\/blog\/#website","url":"https:\/\/www.borgione.it\/blog\/","name":"Blog - Borgione Centro Didattico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.borgione.it\/blog\/?s=%7Bsearch_term_string%7D"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.borgione.it\/blog\/#\/schema\/person\/035ab9f79e06957439022325c63541eb","name":"Redazione","url":"https:\/\/www.borgione.it\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/2536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/comments?post=2536"}],"version-history":[{"count":7,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/2536\/revisions"}],"predecessor-version":[{"id":4908,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/posts\/2536\/revisions\/4908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/media\/2537"}],"wp:attachment":[{"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/media?parent=2536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/categories?post=2536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.borgione.it\/blog\/wp-json\/wp\/v2\/tags?post=2536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}